{"id":84543,"date":"2019-04-28T13:52:00","date_gmt":"2019-04-28T04:52:00","guid":{"rendered":"https:\/\/asez.org\/future-leader-forum-virginia-us\/"},"modified":"2026-05-13T15:25:03","modified_gmt":"2026-05-13T06:25:03","slug":"future-leader-forum-virginia-us","status":"publish","type":"post","link":"https:\/\/asez.org\/es\/future-leader-forum-virginia-us\/","title":{"rendered":"Foro de Futuros L\u00edderes de ASEZ en Virginia, EE. UU.,"},"content":{"rendered":"<p>El 28 de abril, se llev\u00f3 a cabo el Foro de Futuros L\u00edderes de ASEZ en la Iglesia de Dios de Newport News, VA, EE. UU. Fue para educar a los universitarios, los protagonistas del ma\u00f1ana, como los futuros l\u00edderes que tomar\u00e1n la delantera en la reducci\u00f3n y prevenci\u00f3n del crimen, y para el desarrollo de planes para fomentar la participaci\u00f3n ciudadana. Los oficiales de polic\u00eda de la ciudad, los miembros de ASEZ y m\u00e1s de 90 residentes se reunieron para reducir el crimen y crear una comunidad segura.<\/p>\n<figure>\n              <picture class=\"copyright\">\n                <source media=\"(max-width:450px)\" srcset=\"https:\/\/asez.org\/wp-content\/themes\/watv\/images\/posts\/news_190428_01.jpg\">\n                <img decoding=\"async\" src=\"https:\/\/asez.org\/wp-content\/themes\/watv\/images\/posts\/news_190428_01.jpg\"\n                  srcset=\"https:\/\/asez.org\/wp-content\/themes\/watv\/images\/posts\/news_190428_01.jpg,\n                          https:\/\/asez.org\/wp-content\/themes\/watv\/images\/posts\/news_190428_01.jpg 2x\">\n              <\/picture><\/figure>\n<p>En este foro, que formaba parte del proyecto \u201cReduzcamos Juntos el Crimen\u201d de ASEZ, los ponentes fueron Steven Drew, jefe de polic\u00eda de Newport News; el alguacil Gabriel Morgan; Daniel Warman, profesor de la Universidad Estatal de Norfolk; y Jeffrey Riddle, abogado local. Enfatizaron la importancia de la educaci\u00f3n y la participaci\u00f3n en la reducci\u00f3n y prevenci\u00f3n del crimen. Adem\u00e1s, se\u00f1alaron que la preocupaci\u00f3n y la consideraci\u00f3n basadas en el amor de una madre, pueden reducir la brecha entre los miembros de la comunidad y sus conflictos.<\/p>\n<div class=\"divide\">\n <figure>\n              <picture class=\"copyright\">\n                <source media=\"(max-width:450px)\" srcset=\"https:\/\/asez.org\/wp-content\/themes\/watv\/images\/posts\/news_190428_02.jpg\">\n                <img decoding=\"async\" src=\"https:\/\/asez.org\/wp-content\/themes\/watv\/images\/posts\/news_190428_02.jpg\"\n                  srcset=\"https:\/\/asez.org\/wp-content\/themes\/watv\/images\/posts\/news_190428_02.jpg,\n                          https:\/\/asez.org\/wp-content\/themes\/watv\/images\/posts\/news_190428_02.jpg 2x\">\n              <\/picture><\/figure>\n <figure>\n              <picture class=\"copyright\">\n                <source media=\"(max-width:450px)\" srcset=\"https:\/\/asez.org\/wp-content\/themes\/watv\/images\/posts\/news_190428_03.jpg\">\n                <img decoding=\"async\" src=\"https:\/\/asez.org\/wp-content\/themes\/watv\/images\/posts\/news_190428_03.jpg\"\n                  srcset=\"https:\/\/asez.org\/wp-content\/themes\/watv\/images\/posts\/news_190428_03.jpg,\n                          https:\/\/asez.org\/wp-content\/themes\/watv\/images\/posts\/news_190428_03.jpg 2x\">\n              <\/picture><\/figure>\n<\/div>\n<p>Despu\u00e9s de sus presentaciones, los oradores acordaron cooperar con ASEZ a trav\u00e9s de sus firmas de apoyo. El alguacil Gabriel Morgan coment\u00f3: \u201cSent\u00ed un verdadero deseo de generar un cambio. Esta organizaci\u00f3n (ASEZ) comprende claramente los problemas urgentes de la sociedad, y eso ha encendido a\u00fan m\u00e1s mi pasi\u00f3n\u201d.<\/p>\n<figure>\n              <picture class=\"copyright\">\n                <source media=\"(max-width:450px)\" srcset=\"https:\/\/asez.org\/wp-content\/themes\/watv\/images\/posts\/news_190428_04.jpg\">\n                <img decoding=\"async\" src=\"https:\/\/asez.org\/wp-content\/themes\/watv\/images\/posts\/news_190428_04.jpg\"\n                  srcset=\"https:\/\/asez.org\/wp-content\/themes\/watv\/images\/posts\/news_190428_04.jpg,\n                          https:\/\/asez.org\/wp-content\/themes\/watv\/images\/posts\/news_190428_04.jpg 2x\">\n              <\/picture><\/figure>\n<p>Este d\u00eda, los participantes discutieron los planes viables para la prevenci\u00f3n del delito en la vida diaria, y dieron el primer paso juntos para crear una sociedad segura con el coraz\u00f3n de una madre.<\/p>\n","protected":false},"excerpt":{"rendered":"El 28 de abril, se llev\u00f3 a cabo el Foro de Futuros L\u00edderes de ASEZ en la Iglesia de Dios de Newport News, VA, EE. UU. Fue para educar a los universitarios, los protagonistas del ma\u00f1ana, como los futuros l\u00edderes que tomar\u00e1n la delantera en la reducci\u00f3n y prevenci\u00f3n del crimen, y para el desarrollo&#8230;","protected":false},"author":4,"featured_media":84544,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"post-type\/overlay-half-dark.php","format":"standard","meta":{"footnotes":""},"categories":[214,215],"tags":[],"class_list":["post-84543","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-newsroom","category-crime-prevention"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Foro de Futuros L\u00edderes de ASEZ en Virginia, EE. UU., - ASEZ<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/asez.org\/es\/future-leader-forum-virginia-us\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Foro de Futuros L\u00edderes de ASEZ en Virginia, EE. UU., - ASEZ\" \/>\n<meta property=\"og:description\" content=\"El 28 de abril, se llev\u00f3 a cabo el Foro de Futuros L\u00edderes de ASEZ en la Iglesia de Dios de Newport News, VA, EE. UU. Fue para educar a los universitarios, los protagonistas del ma\u00f1ana, como los futuros l\u00edderes que tomar\u00e1n la delantera en la reducci\u00f3n y prevenci\u00f3n del crimen, y para el desarrollo...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/asez.org\/es\/future-leader-forum-virginia-us\/\" \/>\n<meta property=\"og:site_name\" content=\"ASEZ\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-28T04:52:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T06:25:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/asez.org\/wp-content\/uploads\/2019\/04\/news_190428_05-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hj\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hj\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/asez.org\/es\/future-leader-forum-virginia-us\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/asez.org\/es\/future-leader-forum-virginia-us\/\"},\"author\":{\"name\":\"hj\",\"@id\":\"https:\/\/asez.org\/es\/#\/schema\/person\/3dc45679e0457bb64535a72049829669\"},\"headline\":\"Foro de Futuros L\u00edderes de ASEZ en Virginia, EE. UU.,\",\"datePublished\":\"2019-04-28T04:52:00+00:00\",\"dateModified\":\"2026-05-13T06:25:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/asez.org\/es\/future-leader-forum-virginia-us\/\"},\"wordCount\":323,\"image\":{\"@id\":\"https:\/\/asez.org\/es\/future-leader-forum-virginia-us\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/asez.org\/wp-content\/uploads\/2019\/04\/news_190428_05-1.jpg\",\"articleSection\":[\"Sala de prensa\",\"Prevenci\u00f3n del crimen\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/asez.org\/es\/future-leader-forum-virginia-us\/\",\"url\":\"https:\/\/asez.org\/es\/future-leader-forum-virginia-us\/\",\"name\":\"Foro de Futuros L\u00edderes de ASEZ en Virginia, EE. UU., - ASEZ\",\"isPartOf\":{\"@id\":\"https:\/\/asez.org\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/asez.org\/es\/future-leader-forum-virginia-us\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/asez.org\/es\/future-leader-forum-virginia-us\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/asez.org\/wp-content\/uploads\/2019\/04\/news_190428_05-1.jpg\",\"datePublished\":\"2019-04-28T04:52:00+00:00\",\"dateModified\":\"2026-05-13T06:25:03+00:00\",\"author\":{\"@id\":\"https:\/\/asez.org\/es\/#\/schema\/person\/3dc45679e0457bb64535a72049829669\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/asez.org\/es\/future-leader-forum-virginia-us\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/asez.org\/es\/future-leader-forum-virginia-us\/#primaryimage\",\"url\":\"https:\/\/asez.org\/wp-content\/uploads\/2019\/04\/news_190428_05-1.jpg\",\"contentUrl\":\"https:\/\/asez.org\/wp-content\/uploads\/2019\/04\/news_190428_05-1.jpg\",\"width\":2400,\"height\":1600},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/asez.org\/es\/#website\",\"url\":\"https:\/\/asez.org\/es\/\",\"name\":\"ASEZ\",\"description\":\"\ud558\ub098\ub2d8\uc758\uad50\ud68c \ub300\ud559\uc0dd\ubd09\uc0ac\ub2e8\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/asez.org\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/asez.org\/es\/#\/schema\/person\/3dc45679e0457bb64535a72049829669\",\"name\":\"hj\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Foro de Futuros L\u00edderes de ASEZ en Virginia, EE. UU., - ASEZ","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/asez.org\/es\/future-leader-forum-virginia-us\/","og_locale":"es_ES","og_type":"article","og_title":"Foro de Futuros L\u00edderes de ASEZ en Virginia, EE. UU., - ASEZ","og_description":"El 28 de abril, se llev\u00f3 a cabo el Foro de Futuros L\u00edderes de ASEZ en la Iglesia de Dios de Newport News, VA, EE. UU. Fue para educar a los universitarios, los protagonistas del ma\u00f1ana, como los futuros l\u00edderes que tomar\u00e1n la delantera en la reducci\u00f3n y prevenci\u00f3n del crimen, y para el desarrollo...","og_url":"https:\/\/asez.org\/es\/future-leader-forum-virginia-us\/","og_site_name":"ASEZ","article_published_time":"2019-04-28T04:52:00+00:00","article_modified_time":"2026-05-13T06:25:03+00:00","og_image":[{"width":2400,"height":1600,"url":"https:\/\/asez.org\/wp-content\/uploads\/2019\/04\/news_190428_05-1.jpg","type":"image\/jpeg"}],"author":"hj","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"hj","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/asez.org\/es\/future-leader-forum-virginia-us\/#article","isPartOf":{"@id":"https:\/\/asez.org\/es\/future-leader-forum-virginia-us\/"},"author":{"name":"hj","@id":"https:\/\/asez.org\/es\/#\/schema\/person\/3dc45679e0457bb64535a72049829669"},"headline":"Foro de Futuros L\u00edderes de ASEZ en Virginia, EE. UU.,","datePublished":"2019-04-28T04:52:00+00:00","dateModified":"2026-05-13T06:25:03+00:00","mainEntityOfPage":{"@id":"https:\/\/asez.org\/es\/future-leader-forum-virginia-us\/"},"wordCount":323,"image":{"@id":"https:\/\/asez.org\/es\/future-leader-forum-virginia-us\/#primaryimage"},"thumbnailUrl":"https:\/\/asez.org\/wp-content\/uploads\/2019\/04\/news_190428_05-1.jpg","articleSection":["Sala de prensa","Prevenci\u00f3n del crimen"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/asez.org\/es\/future-leader-forum-virginia-us\/","url":"https:\/\/asez.org\/es\/future-leader-forum-virginia-us\/","name":"Foro de Futuros L\u00edderes de ASEZ en Virginia, EE. UU., - ASEZ","isPartOf":{"@id":"https:\/\/asez.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/asez.org\/es\/future-leader-forum-virginia-us\/#primaryimage"},"image":{"@id":"https:\/\/asez.org\/es\/future-leader-forum-virginia-us\/#primaryimage"},"thumbnailUrl":"https:\/\/asez.org\/wp-content\/uploads\/2019\/04\/news_190428_05-1.jpg","datePublished":"2019-04-28T04:52:00+00:00","dateModified":"2026-05-13T06:25:03+00:00","author":{"@id":"https:\/\/asez.org\/es\/#\/schema\/person\/3dc45679e0457bb64535a72049829669"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/asez.org\/es\/future-leader-forum-virginia-us\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/asez.org\/es\/future-leader-forum-virginia-us\/#primaryimage","url":"https:\/\/asez.org\/wp-content\/uploads\/2019\/04\/news_190428_05-1.jpg","contentUrl":"https:\/\/asez.org\/wp-content\/uploads\/2019\/04\/news_190428_05-1.jpg","width":2400,"height":1600},{"@type":"WebSite","@id":"https:\/\/asez.org\/es\/#website","url":"https:\/\/asez.org\/es\/","name":"ASEZ","description":"\ud558\ub098\ub2d8\uc758\uad50\ud68c \ub300\ud559\uc0dd\ubd09\uc0ac\ub2e8","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/asez.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/asez.org\/es\/#\/schema\/person\/3dc45679e0457bb64535a72049829669","name":"hj"}]}},"fimg_url":"https:\/\/asez.org\/wp-content\/uploads\/2019\/04\/news_190428_05-1.jpg","featured_image_url":"https:\/\/asez.org\/wp-content\/uploads\/2019\/04\/news_190428_05-1.jpg","_links":{"self":[{"href":"https:\/\/asez.org\/es\/wp-json\/wp\/v2\/posts\/84543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/asez.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asez.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asez.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/asez.org\/es\/wp-json\/wp\/v2\/comments?post=84543"}],"version-history":[{"count":1,"href":"https:\/\/asez.org\/es\/wp-json\/wp\/v2\/posts\/84543\/revisions"}],"predecessor-version":[{"id":84545,"href":"https:\/\/asez.org\/es\/wp-json\/wp\/v2\/posts\/84543\/revisions\/84545"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asez.org\/es\/wp-json\/wp\/v2\/media\/84544"}],"wp:attachment":[{"href":"https:\/\/asez.org\/es\/wp-json\/wp\/v2\/media?parent=84543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asez.org\/es\/wp-json\/wp\/v2\/categories?post=84543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asez.org\/es\/wp-json\/wp\/v2\/tags?post=84543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}